{"id":17045,"date":"2020-11-05T09:22:44","date_gmt":"2020-11-05T08:22:44","guid":{"rendered":"https:\/\/test.praim.com\/?page_id=17045"},"modified":"2024-04-24T09:55:15","modified_gmt":"2024-04-24T07:55:15","slug":"sanita","status":"publish","type":"page","link":"https:\/\/www.praim.com\/it\/soluzioni\/sanita\/","title":{"rendered":"Soluzioni informatiche dedicate al settore della sanit\u00e0"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container hundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-top:0px;--awb-padding-right:0px;--awb-padding-bottom:0px;--awb-padding-left:0px;--awb-margin-top:0px;--awb-margin-bottom:30px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"width:104% !important;max-width:104% !important;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-padding-top:10px;--awb-padding-right:10px;--awb-padding-bottom:10px;--awb-padding-left:10px;--awb-bg-size:cover;--awb-border-color:#000000;--awb-border-top:0;--awb-border-right:0;--awb-border-bottom:0;--awb-border-left:0;--awb-border-style:solid;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-content-boxes content-boxes columns row fusion-columns-2 fusion-columns-total-2 fusion-content-boxes-1 content-boxes-icon-with-title content-left\" style=\"--awb-backgroundcolor:#f8fafc;--awb-body-color:#000000;--awb-title-color:#41a1d0;--awb-margin-bottom:0px;--awb-hover-accent-color:#a0ce4e;--awb-circle-hover-accent-color:#a0ce4e;\" data-animationOffset=\"top-into-view\"><div style=\"--awb-backgroundcolor:#f8fafc;\" class=\"fusion-column content-box-column content-box-column content-box-column-1 col-lg-6 col-md-6 col-sm-6 fusion-content-box-hover content-box-column-first-in-row\"><div class=\"col content-box-wrapper content-wrapper-background link-area-link-icon icon-hover-animation-fade\" data-animationOffset=\"top-into-view\"><div class=\"heading heading-with-icon icon-left\"><div aria-hidden=\"true\" class=\"image\"><img decoding=\"async\" class=\"lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" data-orig-src=\"https:\/\/www.praim.com\/wp-content\/uploads\/2021\/04\/Icona-Bisogni-Praim-e1617973578196.png\" width=\"150\" height=\"150\" alt=\"Bisogni Praim\" \/><\/div><h2 class=\"content-box-heading fusion-responsive-typography-calculated\" style=\"--h2_typography-font-size:24px;--fontSize:24;line-height:var(--awb-typography2-line-height);\">Le tue necessit\u00e0<\/h2><\/div><div class=\"fusion-clearfix\"><\/div><div class=\"content-container\">\n<p>Accesso sicuro, veloce e flessibile alle risorse con postazioni di lavoro certificate secondo gli standard medicali e che resistono a manomissioni e malware, ma anche:<\/p>\n<ul>\n<li>Endpoint distribuiti e con usi eterogenei<\/li>\n<li>Dispositivi con certificazioni specifiche<\/li>\n<li>Supporto a periferiche specifiche del contesto medico<\/li>\n<li>Velocit\u00e0 di accesso ai sistemi e identificazione<\/li>\n<li>Diversificazione degli accessi e dei profili<\/li>\n<li>Massima sicurezza e privacy<\/li>\n<li>Massima affidabilit\u00e0 e stabilit\u00e0<\/li>\n<li>Mobilit\u00e0 delle postazioni<\/li>\n<li>Gestione multi-dominio<\/li>\n<li>Aggiornamenti di sicurezza<\/li>\n<\/ul>\n<\/div><\/div><\/div><div style=\"--awb-backgroundcolor:#f8fafc;\" class=\"fusion-column content-box-column content-box-column content-box-column-2 col-lg-6 col-md-6 col-sm-6 fusion-content-box-hover content-box-column-last content-box-column-last-in-row\"><div class=\"col content-box-wrapper content-wrapper-background link-area-link-icon icon-hover-animation-fade\" data-animationOffset=\"top-into-view\"><div class=\"heading heading-with-icon icon-left\"><div aria-hidden=\"true\" class=\"image\"><img decoding=\"async\" class=\"lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" data-orig-src=\"https:\/\/www.praim.com\/wp-content\/uploads\/2021\/04\/Icona-Soluzioni-Praim-e1617973611621.png\" width=\"150\" height=\"150\" alt=\"Soluzioni Praim\" \/><\/div><h2 class=\"content-box-heading fusion-responsive-typography-calculated\" style=\"--h2_typography-font-size:24px;--fontSize:24;line-height:var(--awb-typography2-line-height);\">Le nostre soluzioni<\/h2><\/div><div class=\"fusion-clearfix\"><\/div><div class=\"content-container\">\n<p>Praim ti offre postazioni di lavoro con le migliori feature per la tua attivit\u00e0:<\/p>\n<ul>\n<li><a title=\"ThinMan\" href=\"https:\/\/www.praim.com\/it\/soluzioni\/software\/thinman\/\"><strong>ThinMan:<\/strong><\/a> per una gestione unificata di tutti gli endpoint, indipendentemente dalla loro tipologia.<\/li>\n<li><strong><a title=\"Feature Pack ThinMan\" href=\"https:\/\/www.praim.com\/it\/soluzioni\/software\/feature-pack\">Feature Pack User+:<\/a><\/strong> per un&#8217;autenticazione e un accesso alle postazioni rapido, sicuro e con esperienza semplificata.<\/li>\n<li><strong><a title=\"Agile4PC\" href=\"https:\/\/www.praim.com\/it\/soluzioni\/software\/feature-pack\">Feature Pack Admin+:<\/a> <\/strong>per utilizzare tutte le feature avanzate di business continuity, sicurezza e management.<\/li>\n<li><a href=\"https:\/\/www.praim.com\/it\/soluzioni\/thinclient\/expertcenter\/\"><strong>ExpertCenter:<\/strong><\/a> il Thin Client ideale per creare chioschi affidabili e silenziosi da trasportare ovunque, facilmente.<\/li>\n<\/ul>\n<\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":7,"featured_media":24682,"parent":7126,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"100-width.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-17045","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Soluzioni informatiche hardware e software per la sanit\u00e0 | Praim<\/title>\n<meta name=\"description\" content=\"Scopri le soluzioni informatiche Praim dedicate al settore ospedaliero dove \u00e8 cruciale assicurare alte prestazioni e sicurezza dei dati.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.praim.com\/it\/soluzioni\/sanita\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Soluzioni informatiche hardware e software per la sanit\u00e0 | Praim\" \/>\n<meta property=\"og:description\" content=\"Scopri le soluzioni informatiche Praim dedicate al settore ospedaliero dove \u00e8 cruciale assicurare alte prestazioni e sicurezza dei dati.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.praim.com\/it\/soluzioni\/sanita\/\" \/>\n<meta property=\"og:site_name\" content=\"Praim\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-24T07:55:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.praim.com\/wp-content\/uploads\/2022\/05\/Banner-Pagina-Sanita-Praim-1920x350-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"350\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.praim.com\\\/it\\\/soluzioni\\\/sanita\\\/\",\"url\":\"https:\\\/\\\/www.praim.com\\\/it\\\/soluzioni\\\/sanita\\\/\",\"name\":\"Soluzioni informatiche hardware e software per la sanit\u00e0 | Praim\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.praim.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.praim.com\\\/it\\\/soluzioni\\\/sanita\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.praim.com\\\/it\\\/soluzioni\\\/sanita\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.praim.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Banner-Pagina-Sanita-Praim-1920x350-1.jpg\",\"datePublished\":\"2020-11-05T08:22:44+00:00\",\"dateModified\":\"2024-04-24T07:55:15+00:00\",\"description\":\"Scopri le soluzioni informatiche Praim dedicate al settore ospedaliero dove \u00e8 cruciale assicurare alte prestazioni e sicurezza dei dati.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.praim.com\\\/it\\\/soluzioni\\\/sanita\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.praim.com\\\/it\\\/soluzioni\\\/sanita\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.praim.com\\\/it\\\/soluzioni\\\/sanita\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.praim.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Banner-Pagina-Sanita-Praim-1920x350-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.praim.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Banner-Pagina-Sanita-Praim-1920x350-1.jpg\",\"width\":1920,\"height\":350,\"caption\":\"sanit\u00e0\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.praim.com\\\/it\\\/soluzioni\\\/sanita\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.praim.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Soluzioni\",\"item\":\"https:\\\/\\\/www.praim.com\\\/it\\\/soluzioni\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Soluzioni informatiche dedicate al settore della sanit\u00e0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.praim.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.praim.com\\\/it\\\/\",\"name\":\"Praim\",\"description\":\"Smart Access to your Cloud\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.praim.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.praim.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.praim.com\\\/it\\\/#organization\",\"name\":\"Praim srl\",\"url\":\"https:\\\/\\\/www.praim.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.praim.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.praim.com\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/praim-logo.png\",\"contentUrl\":\"https:\\\/\\\/www.praim.com\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/praim-logo.png\",\"width\":230,\"height\":230,\"caption\":\"Praim srl\"},\"image\":{\"@id\":\"https:\\\/\\\/www.praim.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Soluzioni informatiche hardware e software per la sanit\u00e0 | Praim","description":"Scopri le soluzioni informatiche Praim dedicate al settore ospedaliero dove \u00e8 cruciale assicurare alte prestazioni e sicurezza dei dati.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.praim.com\/it\/soluzioni\/sanita\/","og_locale":"it_IT","og_type":"article","og_title":"Soluzioni informatiche hardware e software per la sanit\u00e0 | Praim","og_description":"Scopri le soluzioni informatiche Praim dedicate al settore ospedaliero dove \u00e8 cruciale assicurare alte prestazioni e sicurezza dei dati.","og_url":"https:\/\/www.praim.com\/it\/soluzioni\/sanita\/","og_site_name":"Praim","article_modified_time":"2024-04-24T07:55:15+00:00","og_image":[{"width":1920,"height":350,"url":"https:\/\/www.praim.com\/wp-content\/uploads\/2022\/05\/Banner-Pagina-Sanita-Praim-1920x350-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.praim.com\/it\/soluzioni\/sanita\/","url":"https:\/\/www.praim.com\/it\/soluzioni\/sanita\/","name":"Soluzioni informatiche hardware e software per la sanit\u00e0 | Praim","isPartOf":{"@id":"https:\/\/www.praim.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.praim.com\/it\/soluzioni\/sanita\/#primaryimage"},"image":{"@id":"https:\/\/www.praim.com\/it\/soluzioni\/sanita\/#primaryimage"},"thumbnailUrl":"https:\/\/www.praim.com\/wp-content\/uploads\/2022\/05\/Banner-Pagina-Sanita-Praim-1920x350-1.jpg","datePublished":"2020-11-05T08:22:44+00:00","dateModified":"2024-04-24T07:55:15+00:00","description":"Scopri le soluzioni informatiche Praim dedicate al settore ospedaliero dove \u00e8 cruciale assicurare alte prestazioni e sicurezza dei dati.","breadcrumb":{"@id":"https:\/\/www.praim.com\/it\/soluzioni\/sanita\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.praim.com\/it\/soluzioni\/sanita\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.praim.com\/it\/soluzioni\/sanita\/#primaryimage","url":"https:\/\/www.praim.com\/wp-content\/uploads\/2022\/05\/Banner-Pagina-Sanita-Praim-1920x350-1.jpg","contentUrl":"https:\/\/www.praim.com\/wp-content\/uploads\/2022\/05\/Banner-Pagina-Sanita-Praim-1920x350-1.jpg","width":1920,"height":350,"caption":"sanit\u00e0"},{"@type":"BreadcrumbList","@id":"https:\/\/www.praim.com\/it\/soluzioni\/sanita\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.praim.com\/it\/"},{"@type":"ListItem","position":2,"name":"Soluzioni","item":"https:\/\/www.praim.com\/it\/soluzioni\/"},{"@type":"ListItem","position":3,"name":"Soluzioni informatiche dedicate al settore della sanit\u00e0"}]},{"@type":"WebSite","@id":"https:\/\/www.praim.com\/it\/#website","url":"https:\/\/www.praim.com\/it\/","name":"Praim","description":"Smart Access to your Cloud","publisher":{"@id":"https:\/\/www.praim.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.praim.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.praim.com\/it\/#organization","name":"Praim srl","url":"https:\/\/www.praim.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.praim.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.praim.com\/wp-content\/uploads\/2019\/12\/praim-logo.png","contentUrl":"https:\/\/www.praim.com\/wp-content\/uploads\/2019\/12\/praim-logo.png","width":230,"height":230,"caption":"Praim srl"},"image":{"@id":"https:\/\/www.praim.com\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.praim.com\/it\/wp-json\/wp\/v2\/pages\/17045","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.praim.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.praim.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.praim.com\/it\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.praim.com\/it\/wp-json\/wp\/v2\/comments?post=17045"}],"version-history":[{"count":0,"href":"https:\/\/www.praim.com\/it\/wp-json\/wp\/v2\/pages\/17045\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/www.praim.com\/it\/wp-json\/wp\/v2\/pages\/7126"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.praim.com\/it\/wp-json\/wp\/v2\/media\/24682"}],"wp:attachment":[{"href":"https:\/\/www.praim.com\/it\/wp-json\/wp\/v2\/media?parent=17045"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}